{"id":614,"date":"2021-12-03T12:11:36","date_gmt":"2021-12-03T12:11:36","guid":{"rendered":"https:\/\/www.jobmenge.de\/faq\/?p=614"},"modified":"2021-12-07T14:00:23","modified_gmt":"2021-12-07T14:00:23","slug":"fallen-extra-anfahrtskosten-fuer-die-tragehelfer-an","status":"publish","type":"post","link":"https:\/\/www.jobmenge.de\/faq\/tragehelfer\/fallen-extra-anfahrtskosten-fuer-die-tragehelfer-an-studentenvermittlung-jobmenge","title":{"rendered":"Fallen extra Anfahrtskosten f\u00fcr die Tragehelfer an?"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">In der Regel keine extra Anfahrtskosten<\/h2>\n\n\n\n<p>In der Regel m\u00fcssen Sie als Auftraggeber keine Anfahrtskosten f\u00fcr die <a title=\"Tragehelfer\" href=\"\/tragehelfer\/\">Tragehelfer<\/a> \u00fcbernehmen. Wir bem\u00fchen uns darum, Ihnen die <a title=\"Tragehelfer\" href=\"\/tragehelfer\/\">Tragehelfer<\/a> direkt aus Ihrem Umkreis zu vermitteln. So vermeiden wir, dass die Helfer lange Anfahrten zum Einsatzort haben.<\/p>\n\n\n\n<p class=\"box tipp\">In Gro\u00dfst\u00e4dten und an Orten mit guter Anbindung durch \u00f6ffentliche Verkehrsmittel fallen <strong>sicher keine Anfahrtskosten<\/strong> an.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Freiwillige \u00dcbernahme der Anfahrtskosten bei kleineren und mit \u00f6ffentlichen Verkehrsmitteln schwer erreichbaren Orten<\/h4>\n\n\n\n<p>Trotz unserer Bem\u00fchungen kann es in Ausnahmef\u00e4llen dazu kommen, dass Ihre <a title=\"Tragehelfer\" href=\"\/tragehelfer\/\">Tragehelfer<\/a> aus etwas weiter entfernten Regionen anfahren m\u00fcssen, da der Einsatzort abgelegen und eventuell mit \u00f6ffentlichen Verkehrsmitteln schwierig erreichbar ist.<\/p>\n\n\n\n<p class=\"box hinweis\">Ist der Einsatzort abgelegen und mit \u00f6ffentlichen Verkehrsmitteln schwer zu erreichen, so ist zu empfehlen, dass Sie als Auftraggeber die Anfahrtskoten f\u00fcr Ihre <a title=\"Tragehelfer\" href=\"\/tragehelfer\/\">Tragehelfer<\/a> auf freiwillige Basis als ein Entgegenkommen \u00fcbernehmen.<\/p>\n\n\n\n<p>Die \u00dcbernahme der Anfahrtskosten k\u00f6nnen Sie bei der Buchung in der Beschreibung erw\u00e4hnen. Dies kann ein angemessener Pauschalbetrag oder einfach die Erstattung der Ticketkosten sein.<\/p>\n\n\n\n<p>Finden Sie jetzt die g\u00fcnstigsten <a title=\"Tragehelfer\" href=\"\/tragehelfer\/\">Tragehelfer<\/a> in Ihrer Region.<\/p>\n\n\n\n<p>\r\n\t\t\t\t\t<div class=\"hotline_box_wrapper\">\r\n\t\t\t\t\t\t<div class=\"inner_box\">\r\n\t\t\t\t\t\t<span class=\"title\">Jetzt telefonisch buchen!<\/span>\r\n\t\t\t\t\t\t<i class=\"ring\"><\/i>\r\n\t\t\t\t\t\t<a class=\"hotline_number\" href=\"tel:+4922838779910\">0228 \/ 38 77 99 10<\/a>\r\n\t\t\t\t\t\t<span class=\"hotline_times\">Mo. - So.: 08:00 - 19:00<\/span>\r\n\t\t\t\t\t\t<\/div> \r\n\t\t\t\t\t<\/div>\r\n\r\n\r\n\r\n\r\n<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der Regel keine extra Anfahrtskosten In der Regel m\u00fcssen Sie als Auftraggeber keine Anfahrtskosten f\u00fcr die Tragehelfer \u00fcbernehmen. Wir bem\u00fchen uns darum, Ihnen die Tragehelfer direkt aus Ihrem Umkreis zu vermitteln. So vermeiden wir, dass die Helfer lange Anfahrten zum Einsatzort haben. In Gro\u00dfst\u00e4dten und an Orten mit guter Anbindung durch \u00f6ffentliche Verkehrsmittel fallen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/www.jobmenge.de\/faq\/wp-json\/wp\/v2\/posts\/614"}],"collection":[{"href":"https:\/\/www.jobmenge.de\/faq\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.jobmenge.de\/faq\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.jobmenge.de\/faq\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.jobmenge.de\/faq\/wp-json\/wp\/v2\/comments?post=614"}],"version-history":[{"count":7,"href":"https:\/\/www.jobmenge.de\/faq\/wp-json\/wp\/v2\/posts\/614\/revisions"}],"predecessor-version":[{"id":636,"href":"https:\/\/www.jobmenge.de\/faq\/wp-json\/wp\/v2\/posts\/614\/revisions\/636"}],"wp:attachment":[{"href":"https:\/\/www.jobmenge.de\/faq\/wp-json\/wp\/v2\/media?parent=614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.jobmenge.de\/faq\/wp-json\/wp\/v2\/categories?post=614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.jobmenge.de\/faq\/wp-json\/wp\/v2\/tags?post=614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}